{"id":24721,"date":"2018-03-22T15:37:38","date_gmt":"2018-03-22T15:37:38","guid":{"rendered":"https:\/\/www.clubvillamar.fr\/blog\/?p=24721"},"modified":"2023-08-18T10:31:20","modified_gmt":"2023-08-18T10:31:20","slug":"cordoue-lespagne-medievale","status":"publish","type":"post","link":"https:\/\/www.clubvillamar.fr\/blog\/espagne\/cordoue-lespagne-medievale\/","title":{"rendered":"Cordoue ou l\u2019Espagne m\u00e9di\u00e9vale"},"content":{"rendered":"<p><img decoding=\"async\" class=\"alignnone size-full wp-image-24722\" src=\"https:\/\/www.clubvillamar.fr\/blog\/wp-content\/uploads\/2018\/03\/Espange.jpg\" alt=\"\" width=\"724\" height=\"483\" srcset=\"https:\/\/www.clubvillamar.fr\/blog\/wp-content\/uploads\/2018\/03\/Espange.jpg 724w, https:\/\/www.clubvillamar.fr\/blog\/wp-content\/uploads\/2018\/03\/Espange-300x200.jpg 300w\" sizes=\"(max-width: 724px) 100vw, 724px\" \/><\/p>\n<p>Une province du sud de l&rsquo;<a href=\"https:\/\/www.clubvillamar.fr\/\">Espagne<\/a>, Cordoue fait partie de la communaut\u00e9 autonome d&rsquo;Andalousie. La province est la plus connue pour sa ville qui partage le m\u00eame nom car elle attire de nombreux touristes chaque ann\u00e9e, mais la partie la plus large autour de l&rsquo;h\u00e9bergement de Cordoue m\u00e9rite d&rsquo;\u00eatre explor\u00e9e et a beaucoup \u00e0 offrir.<\/p>\n<p>L&rsquo;une des plus grandes villes du monde m\u00e9di\u00e9val, Cordoue \u00e9tait la capitale de la p\u00e9ninsule Ib\u00e9rique occup\u00e9e par les musulmans et abrite l&rsquo;une des plus grandes mosqu\u00e9es du monde occidental &#8211; la magnifique Mezquita de Cordoue.<\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-24723\" src=\"https:\/\/www.clubvillamar.fr\/blog\/wp-content\/uploads\/2018\/03\/La-Mezquita.jpg\" alt=\"\" width=\"770\" height=\"430\" srcset=\"https:\/\/www.clubvillamar.fr\/blog\/wp-content\/uploads\/2018\/03\/La-Mezquita.jpg 770w, https:\/\/www.clubvillamar.fr\/blog\/wp-content\/uploads\/2018\/03\/La-Mezquita-300x168.jpg 300w, https:\/\/www.clubvillamar.fr\/blog\/wp-content\/uploads\/2018\/03\/La-Mezquita-768x429.jpg 768w\" sizes=\"(max-width: 770px) 100vw, 770px\" \/><\/p>\n<p>La Mezquita est largement consid\u00e9r\u00e9e comme l&rsquo;une des plus grandes \u0153uvres d&rsquo;architecture islamique au monde, rendue plus exceptionnelle par la cath\u00e9drale qui fut construite en son c\u0153ur plusieurs ann\u00e9es apr\u00e8s la conqu\u00eate chr\u00e9tienne de la ville en 1236.<\/p>\n<p>La ville est parfaite pour ceux qui aimeraient\u00a0 l\u2019explorer \u00e0 pied ou \u00e0 v\u00e9lo, car les rues \u00e9troites entourant la Mezquita sont remplies de belles places, de ruelles \u00e9troites et de bars \u00e0 tapas anim\u00e9s et de vieux bars \u00e0 vin.<\/p>\n<p>Il vaut la peine d&rsquo;explorer ses villages blancs majestueux, ses oliveraies et ses paysages de montagne dans des endroits comme la Sierra de Hornachuelos et les Sierras de Carde\u00f1a et les r\u00e9serves naturelles de Montoro.<\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-24724\" src=\"https:\/\/www.clubvillamar.fr\/blog\/wp-content\/uploads\/2018\/03\/Cordoue.jpg\" alt=\"\" width=\"960\" height=\"640\" srcset=\"https:\/\/www.clubvillamar.fr\/blog\/wp-content\/uploads\/2018\/03\/Cordoue.jpg 960w, https:\/\/www.clubvillamar.fr\/blog\/wp-content\/uploads\/2018\/03\/Cordoue-300x200.jpg 300w, https:\/\/www.clubvillamar.fr\/blog\/wp-content\/uploads\/2018\/03\/Cordoue-768x512.jpg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/p>\n<p>Cordoue poss\u00e8de \u00e9galement une riche tradition gastronomique typique de l&rsquo;int\u00e9rieur, avec plusieurs produits qui ont re\u00e7u le label Appellation d&rsquo;Origine: le jambon cru de Los Pedroches et l&rsquo;huile d&rsquo;olive vierge, par exemple; ainsi que des recettes caract\u00e9ristiques telles que la queue de taureau en compote et le \u00ab\u00a0salmorejo\u00a0\u00bb (sorte de gaspacho \u00e9pais). Ces plats d\u00e9licieux sont parfaits lorsqu&rsquo;ils sont accompagn\u00e9s par les vins de la Route des vins de Montilla-Moriles.<\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-24725\" src=\"https:\/\/www.clubvillamar.fr\/blog\/wp-content\/uploads\/2018\/03\/Sejour.jpg\" alt=\"\" width=\"1386\" height=\"920\" srcset=\"https:\/\/www.clubvillamar.fr\/blog\/wp-content\/uploads\/2018\/03\/Sejour.jpg 1386w, https:\/\/www.clubvillamar.fr\/blog\/wp-content\/uploads\/2018\/03\/Sejour-300x199.jpg 300w, https:\/\/www.clubvillamar.fr\/blog\/wp-content\/uploads\/2018\/03\/Sejour-768x510.jpg 768w, https:\/\/www.clubvillamar.fr\/blog\/wp-content\/uploads\/2018\/03\/Sejour-1024x680.jpg 1024w\" sizes=\"(max-width: 1386px) 100vw, 1386px\" \/><\/p>\n<p>Pour un s\u00e9jour plus culturel en s\u00e9journant dans des locations de vacances \u00e0 Cordoue, la capitale de la province et ses environs ont de beaux joyaux \u00e0 d\u00e9couvrir, par exemple la Mezquita qui a \u00e9t\u00e9 construite en utilisant diff\u00e9rentes hauteurs de piliers. La ville de Cordoue est maintenant un site du patrimoine mondial et il est facile de voir pourquoi avec son architecture, comme \u00e0 la Grande Mosqu\u00e9e et le site arch\u00e9ologique de Medina-Azahara. La forteresse Alc\u00e1zar des Rois Chr\u00e9tiens vaut aussi la peine d&rsquo;\u00eatre visit\u00e9e dans les appartements de vacances de Cordoue: Le b\u00e2timent du XIVe si\u00e8cle a accueilli la famille royale, les tribunaux des lieux saints, une prison civile et une prison militaire. Il poss\u00e8de \u00e9galement de beaux jardins qui pr\u00e9sentent des statues des monarques qui ont \u00e9t\u00e9 li\u00e9s au palais.<\/p>\n<p>Location de vacances Cordoba sont \u00e9galement entour\u00e9s par des possibilit\u00e9s gastronomiques fantastiques. La province est c\u00e9l\u00e8bre pour son vin de Montilla-Moriles et une route expliquant le long processus de la vinification peut \u00eatre prise. Vous aurez l&rsquo;occasion d&rsquo;essayer les vins qui repr\u00e9sentent la r\u00e9gion andalouse, ainsi que go\u00fbter des tapas pour aller avec. L&rsquo;h\u00e9bergement \u00e0 Cordoue est \u00e9galement un excellent point de d\u00e9part car la province est limitrophe de beaucoup d&rsquo;autres en Andalousie, par exemple Grenade, S\u00e9ville et Malaga, vous ne serez donc jamais bloqu\u00e9 pour vos vacances en Espagne. D\u00e9couvrez la <strong><a href=\"https:\/\/www.clubvillamar.fr\/\">location de villa en Espagne<\/a><\/strong> !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une province du sud de l&rsquo;Espagne, Cordoue fait partie de la communaut\u00e9 autonome d&rsquo;Andalousie. La province est la plus connue [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":24722,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[6836,7231],"tags":[7385,7386,7387,7388],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cordoue ou l\u2019Espagne m\u00e9di\u00e9vale - Club Villamar<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.clubvillamar.fr\/blog\/espagne\/cordoue-lespagne-medievale\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cordoue ou l\u2019Espagne m\u00e9di\u00e9vale - Club Villamar\" \/>\n<meta property=\"og:description\" content=\"Une province du sud de l&rsquo;Espagne, Cordoue fait partie de la communaut\u00e9 autonome d&rsquo;Andalousie. La province est la plus connue [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.clubvillamar.fr\/blog\/espagne\/cordoue-lespagne-medievale\/\" \/>\n<meta property=\"og:site_name\" content=\"Club Villamar\" \/>\n<meta property=\"article:published_time\" content=\"2018-03-22T15:37:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-18T10:31:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.clubvillamar.fr\/blog\/wp-content\/uploads\/2018\/03\/Espange.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"724\" \/>\n\t<meta property=\"og:image:height\" content=\"483\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Club Villamar\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Club Villamar\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.clubvillamar.fr\/blog\/espagne\/cordoue-lespagne-medievale\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.clubvillamar.fr\/blog\/espagne\/cordoue-lespagne-medievale\/\"},\"author\":{\"name\":\"Club Villamar\",\"@id\":\"https:\/\/www.clubvillamar.fr\/blog\/#\/schema\/person\/603e65b5e4bf24837757a4b58cfe7b62\"},\"headline\":\"Cordoue ou l\u2019Espagne m\u00e9di\u00e9vale\",\"datePublished\":\"2018-03-22T15:37:38+00:00\",\"dateModified\":\"2023-08-18T10:31:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.clubvillamar.fr\/blog\/espagne\/cordoue-lespagne-medievale\/\"},\"wordCount\":559,\"publisher\":{\"@id\":\"https:\/\/www.clubvillamar.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.clubvillamar.fr\/blog\/espagne\/cordoue-lespagne-medievale\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.clubvillamar.fr\/blog\/wp-content\/uploads\/2018\/03\/Espange.jpg\",\"keywords\":[\"p\u00e9ninsule Ib\u00e9rique\",\"villages blancs majestueux\",\"locations de vacances \u00e0 Cordoue\",\"appartements de vacances de Cordoue\"],\"articleSection\":[\"Espagne\",\"Andalousie\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.clubvillamar.fr\/blog\/espagne\/cordoue-lespagne-medievale\/\",\"url\":\"https:\/\/www.clubvillamar.fr\/blog\/espagne\/cordoue-lespagne-medievale\/\",\"name\":\"Cordoue ou l\u2019Espagne m\u00e9di\u00e9vale - Club Villamar\",\"isPartOf\":{\"@id\":\"https:\/\/www.clubvillamar.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.clubvillamar.fr\/blog\/espagne\/cordoue-lespagne-medievale\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.clubvillamar.fr\/blog\/espagne\/cordoue-lespagne-medievale\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.clubvillamar.fr\/blog\/wp-content\/uploads\/2018\/03\/Espange.jpg\",\"datePublished\":\"2018-03-22T15:37:38+00:00\",\"dateModified\":\"2023-08-18T10:31:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.clubvillamar.fr\/blog\/espagne\/cordoue-lespagne-medievale\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.clubvillamar.fr\/blog\/espagne\/cordoue-lespagne-medievale\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.clubvillamar.fr\/blog\/espagne\/cordoue-lespagne-medievale\/#primaryimage\",\"url\":\"https:\/\/www.clubvillamar.fr\/blog\/wp-content\/uploads\/2018\/03\/Espange.jpg\",\"contentUrl\":\"https:\/\/www.clubvillamar.fr\/blog\/wp-content\/uploads\/2018\/03\/Espange.jpg\",\"width\":724,\"height\":483},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.clubvillamar.fr\/blog\/espagne\/cordoue-lespagne-medievale\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.clubvillamar.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cordoue ou l\u2019Espagne m\u00e9di\u00e9vale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.clubvillamar.fr\/blog\/#website\",\"url\":\"https:\/\/www.clubvillamar.fr\/blog\/\",\"name\":\"Club Villamar\",\"description\":\"D\u00e9tendez-vous au bord de la piscine de votre villa espagnole\",\"publisher\":{\"@id\":\"https:\/\/www.clubvillamar.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.clubvillamar.fr\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.clubvillamar.fr\/blog\/#organization\",\"name\":\"Club Villamar\",\"url\":\"https:\/\/www.clubvillamar.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.clubvillamar.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.clubvillamar.fr\/blog\/wp-content\/uploads\/2017\/10\/placeholder.jpg\",\"contentUrl\":\"https:\/\/www.clubvillamar.fr\/blog\/wp-content\/uploads\/2017\/10\/placeholder.jpg\",\"width\":1000,\"height\":1000,\"caption\":\"Club Villamar\"},\"image\":{\"@id\":\"https:\/\/www.clubvillamar.fr\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.clubvillamar.fr\/blog\/#\/schema\/person\/603e65b5e4bf24837757a4b58cfe7b62\",\"name\":\"Club Villamar\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.clubvillamar.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6b7b837342835f6b0ba134ae80b58a01?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/6b7b837342835f6b0ba134ae80b58a01?s=96&d=mm&r=g\",\"caption\":\"Club Villamar\"},\"sameAs\":[\"https:\/\/www.clubvillamar.fr\"],\"url\":\"https:\/\/www.clubvillamar.fr\/blog\/author\/marketing\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cordoue ou l\u2019Espagne m\u00e9di\u00e9vale - Club Villamar","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.clubvillamar.fr\/blog\/espagne\/cordoue-lespagne-medievale\/","og_locale":"fr_FR","og_type":"article","og_title":"Cordoue ou l\u2019Espagne m\u00e9di\u00e9vale - Club Villamar","og_description":"Une province du sud de l&rsquo;Espagne, Cordoue fait partie de la communaut\u00e9 autonome d&rsquo;Andalousie. La province est la plus connue [&hellip;]","og_url":"https:\/\/www.clubvillamar.fr\/blog\/espagne\/cordoue-lespagne-medievale\/","og_site_name":"Club Villamar","article_published_time":"2018-03-22T15:37:38+00:00","article_modified_time":"2023-08-18T10:31:20+00:00","og_image":[{"width":724,"height":483,"url":"https:\/\/www.clubvillamar.fr\/blog\/wp-content\/uploads\/2018\/03\/Espange.jpg","type":"image\/jpeg"}],"author":"Club Villamar","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Club Villamar","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.clubvillamar.fr\/blog\/espagne\/cordoue-lespagne-medievale\/#article","isPartOf":{"@id":"https:\/\/www.clubvillamar.fr\/blog\/espagne\/cordoue-lespagne-medievale\/"},"author":{"name":"Club Villamar","@id":"https:\/\/www.clubvillamar.fr\/blog\/#\/schema\/person\/603e65b5e4bf24837757a4b58cfe7b62"},"headline":"Cordoue ou l\u2019Espagne m\u00e9di\u00e9vale","datePublished":"2018-03-22T15:37:38+00:00","dateModified":"2023-08-18T10:31:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.clubvillamar.fr\/blog\/espagne\/cordoue-lespagne-medievale\/"},"wordCount":559,"publisher":{"@id":"https:\/\/www.clubvillamar.fr\/blog\/#organization"},"image":{"@id":"https:\/\/www.clubvillamar.fr\/blog\/espagne\/cordoue-lespagne-medievale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.clubvillamar.fr\/blog\/wp-content\/uploads\/2018\/03\/Espange.jpg","keywords":["p\u00e9ninsule Ib\u00e9rique","villages blancs majestueux","locations de vacances \u00e0 Cordoue","appartements de vacances de Cordoue"],"articleSection":["Espagne","Andalousie"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.clubvillamar.fr\/blog\/espagne\/cordoue-lespagne-medievale\/","url":"https:\/\/www.clubvillamar.fr\/blog\/espagne\/cordoue-lespagne-medievale\/","name":"Cordoue ou l\u2019Espagne m\u00e9di\u00e9vale - Club Villamar","isPartOf":{"@id":"https:\/\/www.clubvillamar.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.clubvillamar.fr\/blog\/espagne\/cordoue-lespagne-medievale\/#primaryimage"},"image":{"@id":"https:\/\/www.clubvillamar.fr\/blog\/espagne\/cordoue-lespagne-medievale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.clubvillamar.fr\/blog\/wp-content\/uploads\/2018\/03\/Espange.jpg","datePublished":"2018-03-22T15:37:38+00:00","dateModified":"2023-08-18T10:31:20+00:00","breadcrumb":{"@id":"https:\/\/www.clubvillamar.fr\/blog\/espagne\/cordoue-lespagne-medievale\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.clubvillamar.fr\/blog\/espagne\/cordoue-lespagne-medievale\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.clubvillamar.fr\/blog\/espagne\/cordoue-lespagne-medievale\/#primaryimage","url":"https:\/\/www.clubvillamar.fr\/blog\/wp-content\/uploads\/2018\/03\/Espange.jpg","contentUrl":"https:\/\/www.clubvillamar.fr\/blog\/wp-content\/uploads\/2018\/03\/Espange.jpg","width":724,"height":483},{"@type":"BreadcrumbList","@id":"https:\/\/www.clubvillamar.fr\/blog\/espagne\/cordoue-lespagne-medievale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.clubvillamar.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Cordoue ou l\u2019Espagne m\u00e9di\u00e9vale"}]},{"@type":"WebSite","@id":"https:\/\/www.clubvillamar.fr\/blog\/#website","url":"https:\/\/www.clubvillamar.fr\/blog\/","name":"Club Villamar","description":"D\u00e9tendez-vous au bord de la piscine de votre villa espagnole","publisher":{"@id":"https:\/\/www.clubvillamar.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.clubvillamar.fr\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.clubvillamar.fr\/blog\/#organization","name":"Club Villamar","url":"https:\/\/www.clubvillamar.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.clubvillamar.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.clubvillamar.fr\/blog\/wp-content\/uploads\/2017\/10\/placeholder.jpg","contentUrl":"https:\/\/www.clubvillamar.fr\/blog\/wp-content\/uploads\/2017\/10\/placeholder.jpg","width":1000,"height":1000,"caption":"Club Villamar"},"image":{"@id":"https:\/\/www.clubvillamar.fr\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.clubvillamar.fr\/blog\/#\/schema\/person\/603e65b5e4bf24837757a4b58cfe7b62","name":"Club Villamar","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.clubvillamar.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/6b7b837342835f6b0ba134ae80b58a01?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6b7b837342835f6b0ba134ae80b58a01?s=96&d=mm&r=g","caption":"Club Villamar"},"sameAs":["https:\/\/www.clubvillamar.fr"],"url":"https:\/\/www.clubvillamar.fr\/blog\/author\/marketing\/"}]}},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/www.clubvillamar.fr\/blog\/wp-content\/uploads\/2018\/03\/Espange.jpg","jetpack_shortlink":"https:\/\/wp.me\/p9DamS-6qJ","_links":{"self":[{"href":"https:\/\/www.clubvillamar.fr\/blog\/wp-json\/wp\/v2\/posts\/24721"}],"collection":[{"href":"https:\/\/www.clubvillamar.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.clubvillamar.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.clubvillamar.fr\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.clubvillamar.fr\/blog\/wp-json\/wp\/v2\/comments?post=24721"}],"version-history":[{"count":3,"href":"https:\/\/www.clubvillamar.fr\/blog\/wp-json\/wp\/v2\/posts\/24721\/revisions"}],"predecessor-version":[{"id":30618,"href":"https:\/\/www.clubvillamar.fr\/blog\/wp-json\/wp\/v2\/posts\/24721\/revisions\/30618"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.clubvillamar.fr\/blog\/wp-json\/wp\/v2\/media\/24722"}],"wp:attachment":[{"href":"https:\/\/www.clubvillamar.fr\/blog\/wp-json\/wp\/v2\/media?parent=24721"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.clubvillamar.fr\/blog\/wp-json\/wp\/v2\/categories?post=24721"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.clubvillamar.fr\/blog\/wp-json\/wp\/v2\/tags?post=24721"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}