{"id":28990,"date":"2022-11-02T13:54:04","date_gmt":"2022-11-02T13:54:04","guid":{"rendered":"https:\/\/www.clubvillamar.fr\/blog\/?p=28990"},"modified":"2022-11-02T13:54:08","modified_gmt":"2022-11-02T13:54:08","slug":"tarragone-pied-a-terre-ideal-pour-sillonner-la-costa-dorada","status":"publish","type":"post","link":"https:\/\/www.clubvillamar.fr\/blog\/espagne\/tarragone-pied-a-terre-ideal-pour-sillonner-la-costa-dorada\/","title":{"rendered":"Tarragone, pied \u00e0 terre id\u00e9al pour sillonner la Costa Dorada"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.clubvillamar.fr\/blog\/wp-content\/uploads\/2018\/09\/shutterstock_213422017.jpg\" alt=\"\"\/><\/figure>\n\n\n\n<p>Tarragone est g\u00e9n\u00e9ralement moins connue que <strong><a href=\"https:\/\/www.clubvillamar.fr\/blog\/espagne\/la-placa-espanya\/\" target=\"_blank\" rel=\"noreferrer noopener\">Barcelone <\/a><\/strong>lorsqu\u2019on parle du littoral espagnol, mais Il s\u2019agit d\u2019une ville surprenante\u00a0! Vous y d\u00e9couvrirez une civilisation mill\u00e9naire. D\u00eener sous les vo\u00fbtes du cirque romain, se perdre dans les ruelles de la vieille ville qui pr\u00e9serve toute l&rsquo;essence de la ville m\u00e9di\u00e9vale, ou prendre l&rsquo;ap\u00e9ritif entour\u00e9 de plus de 2000 ans d&rsquo;histoire, voil\u00e0 le v\u00e9ritable patrimoine de Tarragone ! De plus, c\u2019est le pied \u00e0 terre id\u00e9al pour sillonner la Costa Dorada qui regorge de site magnifiques et d\u2019activit\u00e9s en tout genre\u00a0! Voici un aper\u00e7u\u00a0!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Vielle Ville de Tarragone<\/strong><\/h2>\n\n\n\n<p>Si vous <strong><a href=\"https:\/\/www.clubvillamar.fr\/blog\/espagne\/tarragone-en-une-journee\/\" target=\"_blank\" rel=\"noreferrer noopener\">s\u00e9journez \u00e0 Tarragone<\/a><\/strong>, vous serez \u00e9merveill\u00e9 par les beaut\u00e9s que rec\u00e8le cette <strong>ville m\u00e9di\u00e9vale<\/strong>. Les murailles en pierre sont en tr\u00e8s bon \u00e9tat et d\u00e9limitent encore une grande partie de la vieille ville. Entour\u00e9e de remparts construits au IIIe si\u00e8cle avant J.C, la vielle ville vous invite \u00e0 laisser libre cours \u00e0 votre inspiration et d\u00e9ambuler librement dans les petites ruelles \u00e9troites et color\u00e9es. La Cath\u00e9drale est un monument d\u2019une exceptionnelle richesse et accessoirement la plus grande cath\u00e9drale de Catalogne.<\/p>\n\n\n\n<p>De m\u00eame, l\u2019ensemble <strong>arch\u00e9ologique romain de Tarragone<\/strong> est sans aucun doute incontournable\u00a0! Cet \u00e9difice de forme ovale fut construit au IIe si\u00e8cle en bord de mer. Une partie des gradins fut creus\u00e9e dans la roche. De m\u00eame, le Cirque, o\u00f9 se d\u00e9roulaient les courses de chevaux et de chars, est consid\u00e9r\u00e9 comme l&rsquo;un des cirques les mieux conserv\u00e9s d&rsquo;Occident.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Ville Moderne de Tarragone<\/strong><\/h2>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.clubvillamar.fr\/blog\/wp-content\/uploads\/2018\/09\/shutterstock_1145118497.jpg\" alt=\"\"\/><\/figure>\n\n\n\n<p>Comme dans toutes<strong><a href=\"https:\/\/www.clubvillamar.fr\/blog\/espagne\/vacances-en-espagne-pour-lete-2023\/\" target=\"_blank\" rel=\"noreferrer noopener\"> les villes d\u2019Espagne<\/a><\/strong>, la Rambla, avenue principale de la ville, est un lieu o\u00f9 les habitants aiment venir se d\u00e9tendre et se promener en famille. Tout le long de la Rambla Nova et ses rues adjacentes, vous pourrez profiter de l\u2019hospitalit\u00e9 des petits commerces. N\u2019h\u00e9sitez pas \u00e0 visiter les march\u00e9s de Tarragone pour trouver des produits frais. Le march\u00e9 central, proche de la Rambla Nova, est un important \u00e9difice moderniste (Josep M. Pujol, 1915).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Plages de Tarragone<\/strong><\/h2>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.clubvillamar.fr\/blog\/wp-content\/uploads\/2018\/09\/shutterstock_213491959.jpg\" alt=\"\"\/><\/figure>\n\n\n\n<p>Les plages de Tarragone se caract\u00e9risent par un sable tr\u00e8s fin et dor\u00e9, d\u2019o\u00f9 provient le nom de <strong><a href=\"https:\/\/www.clubvillamar.fr\/blog\/espagne\/costa-dorada\/costa-dorada\/\" target=\"_blank\" rel=\"noreferrer noopener\">Costa Dorada<\/a><\/strong>. Les plages et criques de la Costa Dorada ont une tr\u00e8s faible inclinaison vers la mer, ce qui permet de marcher dans l&rsquo;eau et d&rsquo;y nager sans aucun risque. Le confort sur la plage est garanti par un large \u00e9ventail de services, depuis le nettoyage, les analyses de l&rsquo;eau et du sable, jusqu&rsquo;aux restaurants et services de locations de transats et de diff\u00e9rents mat\u00e9riels destin\u00e9s au sport.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Aux alentours de Tarragone<\/strong><\/h2>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.clubvillamar.fr\/blog\/wp-content\/uploads\/2018\/09\/shutterstock_102019108.jpg\" alt=\"\"\/><figcaption>L&rsquo;impressionnant Aqueduc romain<\/figcaption><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\">Aqueduc romain<\/h4>\n\n\n\n<p><strong>L&rsquo;aqueduc romain de Tarragona<\/strong> a \u00e9t\u00e9 class\u00e9 patrimoine de l&rsquo;humanit\u00e9 par l&rsquo;Unesco et vaut v\u00e9ritablement le d\u00e9tour. Pour le visiter, on peut y aller en voiture mais aussi en bus. Cet aqueduc faisait partie du r\u00e9seau d&rsquo;approvisionnement en eau de la ville imp\u00e9riale. Cette impressionnante construction date du r\u00e8gne de l&#8217;empereur Auguste au Ier si\u00e8cle de notre \u00e8re.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Le\u00a0Parc Naturel du Garraf<\/h4>\n\n\n\n<p>Le\u00a0<strong>Parc Naturel du Garraf<\/strong>, d\u00e9limit\u00e9 par des plages de sable et des montagnes, se trouve \u00e0\u00a0Vilanova i la Gelt\u00fa\u00a0et offre un\u00a0environnement et un climat privil\u00e9gi\u00e9,\u00a0id\u00e9al pour ceux qui aiment la nature, faire des promenades, du v\u00e9lo ou exercer des sports nautiques. Le Parc naturel du Garraf offre un\u00a0paysage exotique\u00a0et une\u00a0v\u00e9g\u00e9tation indig\u00e8ne que vous pourrez explorer. La\u00a0richesse naturelle\u00a0du Garraf est l&rsquo;un des\u00a0paradis verts\u00a0de la c\u00f4te m\u00e9diterran\u00e9enne.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Plages paradisiaques<\/h4>\n\n\n\n<p>Les plages de\u00a0Calafell et Segur de Calafell\u00a0ont \u00e9t\u00e9 les premi\u00e8res municipalit\u00e9s de Catalogne \u00e0 avoir obtenu le\u00a0certificat ISO\u00a0pour leur adaptation aux plages du syst\u00e8me de gestion environnementale. Calafell, Segur de Calafell, <strong><a href=\"https:\/\/www.clubvillamar.fr\/blog\/espagne\/sitges-decouvrez-la-costa-dorada-en-espagne\/\" target=\"_blank\" rel=\"noreferrer noopener\">Sitges <\/a><\/strong>et quelques autres municipalit\u00e9s de la Costa Dorada, poss\u00e8dent \u00e9galement des plages\u00a0qui ont obtenu le pavillon bleu.\u00a0La Costa Dorada est donc une\u00a0destination de vacances id\u00e9ale pour les familles avec des enfants.\u00a0Vous aurez largement l\u2019occasion de vous reposer au soleil et de vous d\u00e9fouler en pratiquant votre\u00a0sport nautique\u00a0pr\u00e9f\u00e9r\u00e9 tel que la natation, la voile, le surf, le jet ski, le ski nautique, le kite surf et bien d\u2019autres encore.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Port Aventura<\/h4>\n\n\n\n<p>Si vous aimez les sensation fortes, vous devrez passer une journ\u00e9e \u00e0 <strong><a href=\"https:\/\/www.clubvillamar.fr\/blog\/espagne\/costa-brava\/lloret-de-mar\/1-journee-sensations-fortes-a-port-aventura\/\" target=\"_blank\" rel=\"noreferrer noopener\">Port Aventura<\/a><\/strong>. C\u2019est un parc th\u00e9matique o\u00f9 vous pourrez\u00a0vivre des aventures\u00a0dans la Chine imp\u00e9riale, le Far West sauvage, l&rsquo;exotique Polyn\u00e9sie, le Mexique azt\u00e8que et la belle M\u00e9diterran\u00e9e. Le parc regorge d&rsquo;attractions qui feront exploser vos niveaux d\u2019adr\u00e9naline\u00a0!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Louez une villa de vacances de luxe \u00e0 Tarragona<\/strong><\/h2>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" src=\"https:\/\/www.clubvillamar.fr\/blog\/wp-content\/uploads\/2022\/11\/villa-Nagoya-Costa-Dorada.jpg\" alt=\"villa Nagoya - Costa Dorada\" class=\"wp-image-28993\" width=\"598\" height=\"401\" srcset=\"https:\/\/www.clubvillamar.fr\/blog\/wp-content\/uploads\/2022\/11\/villa-Nagoya-Costa-Dorada.jpg 425w, https:\/\/www.clubvillamar.fr\/blog\/wp-content\/uploads\/2022\/11\/villa-Nagoya-Costa-Dorada-300x201.jpg 300w\" sizes=\"(max-width: 598px) 100vw, 598px\" \/><figcaption><a href=\"https:\/\/www.clubvillamar.fr\/villas\/espagne\/costa-dorada\/miami-platja\/nagoya\" target=\"_blank\" rel=\"noreferrer noopener\">villa Nagoya &#8211; Costa Dorada<\/a><\/figcaption><\/figure><\/div>\n\n\n\n<p>Pour un s\u00e9jour de pur d\u00e9tente, le meilleur conseil que nous pouvons vous donner c\u2019est de louer une villa de vacances. Ceci vous garantit un confort incomparable. Vous \u00eates ainsi libre de vos mouvements et pouvez organiser vos journ\u00e9es comme bon vous semble. Apr\u00e8s une longue excursion, il n\u2019y a rien de tel que de se d\u00e9tendre au bord de sa propre piscine priv\u00e9e avec un bon cocktail \u00e0 la main\u00a0! <strong><a href=\"https:\/\/www.clubvillamar.fr\/\" target=\"_blank\" rel=\"noreferrer noopener\">Club Villamar <\/a><\/strong>est l\u00e0 pour vous aider \u00e0 trouver votre villa id\u00e9ale\u00a0!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tarragone est g\u00e9n\u00e9ralement moins connue que Barcelone lorsqu\u2019on parle du littoral espagnol, mais Il s\u2019agit d\u2019une ville surprenante\u00a0! Vous y [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":25684,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[6836],"tags":[6876,7499,7818],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tarragone, pied \u00e0 terre id\u00e9al pour sillonner la Costa Dorada - Club Villamar<\/title>\n<meta name=\"description\" content=\"Choisissez Tarragone comme pied \u00e0 terre pour sillonner la Costa Dorada et d\u00e9couvrez une ville riche d&#039;une histoire mill\u00e9naire !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.clubvillamar.fr\/blog\/espagne\/tarragone-pied-a-terre-ideal-pour-sillonner-la-costa-dorada\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tarragone, pied \u00e0 terre id\u00e9al pour sillonner la Costa Dorada - Club Villamar\" \/>\n<meta property=\"og:description\" content=\"Choisissez Tarragone comme pied \u00e0 terre pour sillonner la Costa Dorada et d\u00e9couvrez une ville riche d&#039;une histoire mill\u00e9naire !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.clubvillamar.fr\/blog\/espagne\/tarragone-pied-a-terre-ideal-pour-sillonner-la-costa-dorada\/\" \/>\n<meta property=\"og:site_name\" content=\"Club Villamar\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-02T13:54:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-02T13:54:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.clubvillamar.fr\/blog\/wp-content\/uploads\/2018\/08\/Tarragone.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Club Villamar\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Club Villamar\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.clubvillamar.fr\/blog\/espagne\/tarragone-pied-a-terre-ideal-pour-sillonner-la-costa-dorada\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.clubvillamar.fr\/blog\/espagne\/tarragone-pied-a-terre-ideal-pour-sillonner-la-costa-dorada\/\"},\"author\":{\"name\":\"Club Villamar\",\"@id\":\"https:\/\/www.clubvillamar.fr\/blog\/#\/schema\/person\/603e65b5e4bf24837757a4b58cfe7b62\"},\"headline\":\"Tarragone, pied \u00e0 terre id\u00e9al pour sillonner la Costa Dorada\",\"datePublished\":\"2022-11-02T13:54:04+00:00\",\"dateModified\":\"2022-11-02T13:54:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.clubvillamar.fr\/blog\/espagne\/tarragone-pied-a-terre-ideal-pour-sillonner-la-costa-dorada\/\"},\"wordCount\":916,\"publisher\":{\"@id\":\"https:\/\/www.clubvillamar.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.clubvillamar.fr\/blog\/espagne\/tarragone-pied-a-terre-ideal-pour-sillonner-la-costa-dorada\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.clubvillamar.fr\/blog\/wp-content\/uploads\/2018\/08\/Tarragone.jpg\",\"keywords\":[\"espagne\",\"Tarragone\",\"Tarragone espagne\"],\"articleSection\":[\"Espagne\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.clubvillamar.fr\/blog\/espagne\/tarragone-pied-a-terre-ideal-pour-sillonner-la-costa-dorada\/\",\"url\":\"https:\/\/www.clubvillamar.fr\/blog\/espagne\/tarragone-pied-a-terre-ideal-pour-sillonner-la-costa-dorada\/\",\"name\":\"Tarragone, pied \u00e0 terre id\u00e9al pour sillonner la Costa Dorada - Club Villamar\",\"isPartOf\":{\"@id\":\"https:\/\/www.clubvillamar.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.clubvillamar.fr\/blog\/espagne\/tarragone-pied-a-terre-ideal-pour-sillonner-la-costa-dorada\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.clubvillamar.fr\/blog\/espagne\/tarragone-pied-a-terre-ideal-pour-sillonner-la-costa-dorada\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.clubvillamar.fr\/blog\/wp-content\/uploads\/2018\/08\/Tarragone.jpg\",\"datePublished\":\"2022-11-02T13:54:04+00:00\",\"dateModified\":\"2022-11-02T13:54:08+00:00\",\"description\":\"Choisissez Tarragone comme pied \u00e0 terre pour sillonner la Costa Dorada et d\u00e9couvrez une ville riche d'une histoire mill\u00e9naire !\",\"breadcrumb\":{\"@id\":\"https:\/\/www.clubvillamar.fr\/blog\/espagne\/tarragone-pied-a-terre-ideal-pour-sillonner-la-costa-dorada\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.clubvillamar.fr\/blog\/espagne\/tarragone-pied-a-terre-ideal-pour-sillonner-la-costa-dorada\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.clubvillamar.fr\/blog\/espagne\/tarragone-pied-a-terre-ideal-pour-sillonner-la-costa-dorada\/#primaryimage\",\"url\":\"https:\/\/www.clubvillamar.fr\/blog\/wp-content\/uploads\/2018\/08\/Tarragone.jpg\",\"contentUrl\":\"https:\/\/www.clubvillamar.fr\/blog\/wp-content\/uploads\/2018\/08\/Tarragone.jpg\",\"width\":1000,\"height\":667,\"caption\":\"Tarragone\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.clubvillamar.fr\/blog\/espagne\/tarragone-pied-a-terre-ideal-pour-sillonner-la-costa-dorada\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.clubvillamar.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tarragone, pied \u00e0 terre id\u00e9al pour sillonner la Costa Dorada\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.clubvillamar.fr\/blog\/#website\",\"url\":\"https:\/\/www.clubvillamar.fr\/blog\/\",\"name\":\"Club Villamar\",\"description\":\"D\u00e9tendez-vous au bord de la piscine de votre villa espagnole\",\"publisher\":{\"@id\":\"https:\/\/www.clubvillamar.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.clubvillamar.fr\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.clubvillamar.fr\/blog\/#organization\",\"name\":\"Club Villamar\",\"url\":\"https:\/\/www.clubvillamar.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.clubvillamar.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.clubvillamar.fr\/blog\/wp-content\/uploads\/2017\/10\/placeholder.jpg\",\"contentUrl\":\"https:\/\/www.clubvillamar.fr\/blog\/wp-content\/uploads\/2017\/10\/placeholder.jpg\",\"width\":1000,\"height\":1000,\"caption\":\"Club Villamar\"},\"image\":{\"@id\":\"https:\/\/www.clubvillamar.fr\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.clubvillamar.fr\/blog\/#\/schema\/person\/603e65b5e4bf24837757a4b58cfe7b62\",\"name\":\"Club Villamar\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.clubvillamar.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6b7b837342835f6b0ba134ae80b58a01?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/6b7b837342835f6b0ba134ae80b58a01?s=96&d=mm&r=g\",\"caption\":\"Club Villamar\"},\"sameAs\":[\"https:\/\/www.clubvillamar.fr\"],\"url\":\"https:\/\/www.clubvillamar.fr\/blog\/author\/marketing\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tarragone, pied \u00e0 terre id\u00e9al pour sillonner la Costa Dorada - Club Villamar","description":"Choisissez Tarragone comme pied \u00e0 terre pour sillonner la Costa Dorada et d\u00e9couvrez une ville riche d'une histoire mill\u00e9naire !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.clubvillamar.fr\/blog\/espagne\/tarragone-pied-a-terre-ideal-pour-sillonner-la-costa-dorada\/","og_locale":"fr_FR","og_type":"article","og_title":"Tarragone, pied \u00e0 terre id\u00e9al pour sillonner la Costa Dorada - Club Villamar","og_description":"Choisissez Tarragone comme pied \u00e0 terre pour sillonner la Costa Dorada et d\u00e9couvrez une ville riche d'une histoire mill\u00e9naire !","og_url":"https:\/\/www.clubvillamar.fr\/blog\/espagne\/tarragone-pied-a-terre-ideal-pour-sillonner-la-costa-dorada\/","og_site_name":"Club Villamar","article_published_time":"2022-11-02T13:54:04+00:00","article_modified_time":"2022-11-02T13:54:08+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/www.clubvillamar.fr\/blog\/wp-content\/uploads\/2018\/08\/Tarragone.jpg","type":"image\/jpeg"}],"author":"Club Villamar","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Club Villamar","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.clubvillamar.fr\/blog\/espagne\/tarragone-pied-a-terre-ideal-pour-sillonner-la-costa-dorada\/#article","isPartOf":{"@id":"https:\/\/www.clubvillamar.fr\/blog\/espagne\/tarragone-pied-a-terre-ideal-pour-sillonner-la-costa-dorada\/"},"author":{"name":"Club Villamar","@id":"https:\/\/www.clubvillamar.fr\/blog\/#\/schema\/person\/603e65b5e4bf24837757a4b58cfe7b62"},"headline":"Tarragone, pied \u00e0 terre id\u00e9al pour sillonner la Costa Dorada","datePublished":"2022-11-02T13:54:04+00:00","dateModified":"2022-11-02T13:54:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.clubvillamar.fr\/blog\/espagne\/tarragone-pied-a-terre-ideal-pour-sillonner-la-costa-dorada\/"},"wordCount":916,"publisher":{"@id":"https:\/\/www.clubvillamar.fr\/blog\/#organization"},"image":{"@id":"https:\/\/www.clubvillamar.fr\/blog\/espagne\/tarragone-pied-a-terre-ideal-pour-sillonner-la-costa-dorada\/#primaryimage"},"thumbnailUrl":"https:\/\/www.clubvillamar.fr\/blog\/wp-content\/uploads\/2018\/08\/Tarragone.jpg","keywords":["espagne","Tarragone","Tarragone espagne"],"articleSection":["Espagne"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.clubvillamar.fr\/blog\/espagne\/tarragone-pied-a-terre-ideal-pour-sillonner-la-costa-dorada\/","url":"https:\/\/www.clubvillamar.fr\/blog\/espagne\/tarragone-pied-a-terre-ideal-pour-sillonner-la-costa-dorada\/","name":"Tarragone, pied \u00e0 terre id\u00e9al pour sillonner la Costa Dorada - Club Villamar","isPartOf":{"@id":"https:\/\/www.clubvillamar.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.clubvillamar.fr\/blog\/espagne\/tarragone-pied-a-terre-ideal-pour-sillonner-la-costa-dorada\/#primaryimage"},"image":{"@id":"https:\/\/www.clubvillamar.fr\/blog\/espagne\/tarragone-pied-a-terre-ideal-pour-sillonner-la-costa-dorada\/#primaryimage"},"thumbnailUrl":"https:\/\/www.clubvillamar.fr\/blog\/wp-content\/uploads\/2018\/08\/Tarragone.jpg","datePublished":"2022-11-02T13:54:04+00:00","dateModified":"2022-11-02T13:54:08+00:00","description":"Choisissez Tarragone comme pied \u00e0 terre pour sillonner la Costa Dorada et d\u00e9couvrez une ville riche d'une histoire mill\u00e9naire !","breadcrumb":{"@id":"https:\/\/www.clubvillamar.fr\/blog\/espagne\/tarragone-pied-a-terre-ideal-pour-sillonner-la-costa-dorada\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.clubvillamar.fr\/blog\/espagne\/tarragone-pied-a-terre-ideal-pour-sillonner-la-costa-dorada\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.clubvillamar.fr\/blog\/espagne\/tarragone-pied-a-terre-ideal-pour-sillonner-la-costa-dorada\/#primaryimage","url":"https:\/\/www.clubvillamar.fr\/blog\/wp-content\/uploads\/2018\/08\/Tarragone.jpg","contentUrl":"https:\/\/www.clubvillamar.fr\/blog\/wp-content\/uploads\/2018\/08\/Tarragone.jpg","width":1000,"height":667,"caption":"Tarragone"},{"@type":"BreadcrumbList","@id":"https:\/\/www.clubvillamar.fr\/blog\/espagne\/tarragone-pied-a-terre-ideal-pour-sillonner-la-costa-dorada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.clubvillamar.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Tarragone, pied \u00e0 terre id\u00e9al pour sillonner la Costa Dorada"}]},{"@type":"WebSite","@id":"https:\/\/www.clubvillamar.fr\/blog\/#website","url":"https:\/\/www.clubvillamar.fr\/blog\/","name":"Club Villamar","description":"D\u00e9tendez-vous au bord de la piscine de votre villa espagnole","publisher":{"@id":"https:\/\/www.clubvillamar.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.clubvillamar.fr\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.clubvillamar.fr\/blog\/#organization","name":"Club Villamar","url":"https:\/\/www.clubvillamar.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.clubvillamar.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.clubvillamar.fr\/blog\/wp-content\/uploads\/2017\/10\/placeholder.jpg","contentUrl":"https:\/\/www.clubvillamar.fr\/blog\/wp-content\/uploads\/2017\/10\/placeholder.jpg","width":1000,"height":1000,"caption":"Club Villamar"},"image":{"@id":"https:\/\/www.clubvillamar.fr\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.clubvillamar.fr\/blog\/#\/schema\/person\/603e65b5e4bf24837757a4b58cfe7b62","name":"Club Villamar","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.clubvillamar.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/6b7b837342835f6b0ba134ae80b58a01?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6b7b837342835f6b0ba134ae80b58a01?s=96&d=mm&r=g","caption":"Club Villamar"},"sameAs":["https:\/\/www.clubvillamar.fr"],"url":"https:\/\/www.clubvillamar.fr\/blog\/author\/marketing\/"}]}},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/www.clubvillamar.fr\/blog\/wp-content\/uploads\/2018\/08\/Tarragone.jpg","jetpack_shortlink":"https:\/\/wp.me\/p9DamS-7xA","_links":{"self":[{"href":"https:\/\/www.clubvillamar.fr\/blog\/wp-json\/wp\/v2\/posts\/28990"}],"collection":[{"href":"https:\/\/www.clubvillamar.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.clubvillamar.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.clubvillamar.fr\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.clubvillamar.fr\/blog\/wp-json\/wp\/v2\/comments?post=28990"}],"version-history":[{"count":2,"href":"https:\/\/www.clubvillamar.fr\/blog\/wp-json\/wp\/v2\/posts\/28990\/revisions"}],"predecessor-version":[{"id":28997,"href":"https:\/\/www.clubvillamar.fr\/blog\/wp-json\/wp\/v2\/posts\/28990\/revisions\/28997"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.clubvillamar.fr\/blog\/wp-json\/wp\/v2\/media\/25684"}],"wp:attachment":[{"href":"https:\/\/www.clubvillamar.fr\/blog\/wp-json\/wp\/v2\/media?parent=28990"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.clubvillamar.fr\/blog\/wp-json\/wp\/v2\/categories?post=28990"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.clubvillamar.fr\/blog\/wp-json\/wp\/v2\/tags?post=28990"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}